{"id":1909,"count":1,"description":"","link":"https:\/\/drive-smart.com\/es\/blog\/etiquetas\/empleados\/","name":"empleados","slug":"empleados","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/drive-smart.com\/es\/wp-json\/wp\/v2\/tags\/1909","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/drive-smart.com\/es\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/drive-smart.com\/es\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/drive-smart.com\/es\/wp-json\/wp\/v2\/posts?tags=1909"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}