{"id":30310,"date":"2020-03-20T12:55:48","date_gmt":"2020-03-20T11:55:48","guid":{"rendered":"http:\/\/drive-smart.com\/es\/?p=30310"},"modified":"2021-06-30T14:40:22","modified_gmt":"2021-06-30T12:40:22","slug":"multas-conducir-estado-alarma","status":"publish","type":"post","link":"https:\/\/drive-smart.com\/es\/blog\/2020\/03\/20\/multas-conducir-estado-alarma\/","title":{"rendered":"Multas por conducir durante el Estado de Alarma"},"content":{"rendered":"<p>Desde el s\u00e1bado 14 de marzo, Espa\u00f1a se encuentra en <strong>Estado de Alarma<\/strong> a causa del coronavirus. O lo que es lo mismo: toda la poblaci\u00f3n <strong>tenemos la obligaci\u00f3n de permanecer en casa<\/strong>. \u00danicamente podemos salir de ella en algunos supuestos recogidos en el Real Decreto 463\/2020 de 14 de marzo publicado en el BOE.<\/p>\n<p>El decreto establece la <strong>limitaci\u00f3n de conducir por nuestras carreteras. <\/strong>Pero eso no es todo porque\u00a0<strong>desde hoy viernes 20 de marzo<\/strong>, se advierte que <strong>los agentes de seguridad comenzar\u00e1n a multar<\/strong>. De hecho, tanto Polic\u00eda Nacional como las auton\u00f3micas, la Guardia Civil o las polic\u00edas locales ya est\u00e1n estableciendo <strong>controles en las carreteras para vigilar la circulaci\u00f3n<\/strong> y el cumplimiento del estado de alarma.<\/p>\n<p>En DriveSmart nos unimos al #YoMeQuedoEnCasa y al #QuedateEnCasa, por lo que hemos dejado el coche aparcado. Pero, \u00bf<strong>qu\u00e9 puede suceder si desobedecemos la ordenanza<\/strong> y las excepciones contempladas? <strong>Desde hoy, sanciones.<\/strong> \u00bfHasta cu\u00e1ndo? Hasta que dure el confinamiento, por lo que, <strong>por ahora, durante el mes de marzo<\/strong>.<\/p>\n<h4>Multas entre 601 y 10.400 euros<\/h4>\n<p>Seg\u00fan la Ley de Seguridad Ciudadana de 2015,<strong> las multas pueden oscilar entre los 601 y los 30.000 euros<\/strong>. Aunque, en base al grado que se aplicar\u00eda a los conductores \u00fanicamente por <strong><a href=\"https:\/\/drive-smart.com\/es\/blog\/2020\/03\/19\/estudio-covid19-viajes-en-coche-coronavirus\/\" target=\"_blank\" rel=\"noopener noreferrer\">conducir durante el estado de alarma<\/a> no superar\u00eda los 10.400 euros<\/strong>. Se aplica en base a esta ley porque utilizar el coche durante el estado de alarma (salvo en las excepciones contempladas) <strong>se considera desobediencia o resistencia a la autoridad o a sus agentes<\/strong>.\u00a0<\/p>\n<p>La sanci\u00f3n que se est\u00e1 aplicando mayoritariamente por saltarse la cuarentena y coger el coche asciende a los <strong>600 euros<\/strong>. Sin embargo, \u00a0<strong>la multa puede ser mayor si existen agravantes<\/strong> como la alegaci\u00f3n de <strong>datos falsos o inexactos o la negativa a identificarse<\/strong>. En el caso de <strong>reiterar el incumplimiento del confinamiento, la multa se podr\u00eda elevar\u00a0 hasta los 60.00 euros<\/strong>.<\/p>\n<p>ACTUALIZACI\u00d3N: El d\u00eda 15 de abril de 2020 el Ministerio del Interior ha detallado la tabla de sanciones que se aplicar\u00e1n durante el Estado de Alarma:<\/p>\n<p><a href=\"https:\/\/drive-smart.com\/es\/wp-content\/uploads\/2020\/03\/Sanciones-Covid-19-Ministerio.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-30807\" src=\"https:\/\/drive-smart.com\/es\/wp-content\/uploads\/2020\/03\/Sanciones-Covid-19-Ministerio.png\" alt=\"Las sanciones, durante el Estado de Alarma en Espa\u00f1a\" width=\"1323\" height=\"2051\" srcset=\"https:\/\/drive-smart.com\/es\/wp-content\/uploads\/2020\/03\/Sanciones-Covid-19-Ministerio.png 1323w, https:\/\/drive-smart.com\/es\/wp-content\/uploads\/2020\/03\/Sanciones-Covid-19-Ministerio-194x300.png 194w, https:\/\/drive-smart.com\/es\/wp-content\/uploads\/2020\/03\/Sanciones-Covid-19-Ministerio-768x1191.png 768w, https:\/\/drive-smart.com\/es\/wp-content\/uploads\/2020\/03\/Sanciones-Covid-19-Ministerio-661x1024.png 661w\" sizes=\"auto, (max-width: 1323px) 100vw, 1323px\" \/><\/a><\/p>\n<h4>\u00bfPrisi\u00f3n de tres a 18 meses?<\/h4>\n<p>S\u00ed. El <strong>C\u00f3digo Penal, en el art\u00edculo 556<\/strong>, recoge penas de prisi\u00f3n de tres a dieciocho meses a quienes se resistan o desobedezcan gravemente a la autoridad o sus agentes. En el art\u00edculo 550, el mismo texto recoge las penas de c\u00e1rcel de entre uno y cuatro a\u00f1os de internamiento por atentado contra la autoridad, la resistencia y la desobediencia, lo que incluye, literalmente:<\/p>\n<blockquote>\n<p><em>\u00ablos cometidos contra funcionarios docentes o sanitarios que se hallen en el ejercicio de las funciones propias de su cargo\u00bb\u00a0<\/em><\/p>\n<\/blockquote>\n<h4>Excepciones para poder conducir en el estado de alarma<\/h4>\n<p>Recuerda que \u00fanicamente puedes salir de casa y conducir en los siguientes supuestos, que recoge el Real Decreto del Estado de Alarma por coronavirus:<\/p>\n<ul>\n<li>Para ir a <strong>comprar alimentos<\/strong>, a la <strong>farmacia<\/strong> o productos de primera necesidad.<\/li>\n<li>Para asistir a <strong>centros sanitarios o m\u00e9dicos<\/strong>.<\/li>\n<li>Para desplazarse hasta el <strong>centro de trabajo<\/strong> para aquellos que no puedan teletrabajar, incluidas entidades financieras o de seguros.<\/li>\n<li>Para<strong> retornar al lugar habitual de residencia<\/strong> (nunca para ir a una segunda residencia).<\/li>\n<li>Para acudir a la <strong>asistencia o el cuidado de mayores, menores o personas dependientes<\/strong>, con alguna discapacidad o vulnerables.<\/li>\n<li>Por una <strong>causa de fuerza mayor<\/strong> o situaci\u00f3n de necesidad totalmente justificada.<\/li>\n<\/ul>\n<p>Importante: En caso de estar realizando alguna de las seis excepciones antes mencionadas, siempre <strong>se podr\u00e1 acudir hasta una <a href=\"https:\/\/drive-smart.com\/es\/blog\/2015\/01\/07\/si-me-quedo-sin-gasolina-en-un-viaje-me-pueden-multar\/\" target=\"_blank\" rel=\"noopener noreferrer\">gasolinera para repostar<\/a><\/strong>. Recuerda que, adem\u00e1s, <strong>debes circular solo en el coche (solo podr\u00e1s ir acompa\u00f1ado por personas con discapacidad o por alguna causa justificada)<\/strong>. Adem\u00e1s, deber\u00e1s ir siempre documentado (no solo debes llevar el DNI y el carn\u00e9 de conducir) para <strong>justificar un desplazamiento por trabajo, centros sanitarios o de fuerza mayor<\/strong>.<\/p>\n<p>Aunque, por el momento, todas las carreteras del Estado permanecen abiertas al tr\u00e1fico el Gobierno puede limitar en cualquier momento su uso e incluso llegar a cerrar algunas si se considera necesario \u00abpor razones de salud p\u00fablica, seguridad o fluidez del tr\u00e1fico\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desde el s\u00e1bado 14 de marzo, Espa\u00f1a se encuentra en Estado de Alarma a causa del coronavirus. O lo que es lo mismo: toda la poblaci\u00f3n tenemos la obligaci\u00f3n de permanecer en casa. \u00danicamente podemos salir de ella en algunos supuestos recogidos en el Real Decreto 463\/2020 de 14 de marzo publicado en el BOE. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":30327,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1311,85,92],"tags":[142,139,138,2015,2001,2014,204,1627,146,300,2016,140],"class_list":["post-30310","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-me-pueden-multar-si","category-esta-pasando","category-para-ti-conductor","tag-carretera","tag-coche","tag-conducir","tag-control-de-carretera","tag-coronavirus","tag-estado-de-alarma","tag-guardia-civil","tag-movilidad","tag-multa","tag-policia","tag-real-decreto","tag-sancion"],"_links":{"self":[{"href":"https:\/\/drive-smart.com\/es\/wp-json\/wp\/v2\/posts\/30310","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/drive-smart.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/drive-smart.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/drive-smart.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/drive-smart.com\/es\/wp-json\/wp\/v2\/comments?post=30310"}],"version-history":[{"count":11,"href":"https:\/\/drive-smart.com\/es\/wp-json\/wp\/v2\/posts\/30310\/revisions"}],"predecessor-version":[{"id":62257,"href":"https:\/\/drive-smart.com\/es\/wp-json\/wp\/v2\/posts\/30310\/revisions\/62257"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/drive-smart.com\/es\/wp-json\/wp\/v2\/media\/30327"}],"wp:attachment":[{"href":"https:\/\/drive-smart.com\/es\/wp-json\/wp\/v2\/media?parent=30310"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/drive-smart.com\/es\/wp-json\/wp\/v2\/categories?post=30310"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/drive-smart.com\/es\/wp-json\/wp\/v2\/tags?post=30310"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}