{"id":22914,"date":"2019-03-13T10:00:07","date_gmt":"2019-03-13T09:00:07","guid":{"rendered":"http:\/\/drive-smart.com\/es\/?p=22914"},"modified":"2019-06-20T12:30:33","modified_gmt":"2019-06-20T10:30:33","slug":"manual-general-conductor-andaluz","status":"publish","type":"post","link":"https:\/\/drive-smart.com\/es\/blog\/2019\/03\/13\/manual-general-conductor-andaluz\/","title":{"rendered":"Manual general del conductor andaluz"},"content":{"rendered":"<p><strong>Andaluc\u00eda es una tierra especial.<\/strong> Y no lo digo porque me hayan encomendado este art\u00edculo. Tampoco tiene nada que ver que sea m\u00e1s andaluz que el gazpacho\ud83d\ude44. Ya lo han dicho otros. La idiosincrasia de nuestra tierra ha sido explicada por paisanos como\u00a0<strong>Averroes, S\u00e9neca<\/strong> o <strong>Juan Luis de Tarifa<\/strong>. Ha inspirado a genios como <strong>Antonio Machado, Federico Garc\u00eda Lorca o Rafael Alberti<\/strong>. Y est\u00e1 enhebrada con acordes de <strong>Paco de Luc\u00eda y quej\u00edos de Camar\u00f3n<\/strong>.\u00a0<\/p>\n<p><strong>Dentro del paraguas andaluz, se cobijan 8 provincias como 8 soles<\/strong>. Y, aunque tienen cosas en com\u00fan, se revisten con diferencias entre s\u00ed. En este sentido, el habla es uno de los \u00e1mbitos a los que podemos hacer referencia. Y con habla no estamos se\u00f1alando el acento. Que tambi\u00e9n. Sino a las expresiones que son caracter\u00edsticas en cada una de sus variantes. Por ejemplo, depende de donde est\u00e9s, <strong>al ganador del <a href=\"https:\/\/drive-smart.com\/es\/ventajas-smart\/rankings\/reto-drivesmart-enero-2019\/\" target=\"_blank\" rel=\"noopener\">Reto :DriveSmart<\/a> se le puede decir que su conducci\u00f3n es flama, perita o del carajo<\/strong>. \u00bfNo te lo crees? Vamos a contarte c\u00f3mo somos los andaluces al volante. \u00a1Al l\u00edo!<\/p>\n<h4><span style=\"color: #1d2d38;\"><strong>Daltonismo ilustrado<\/strong><\/span><\/h4>\n<p>En Andaluc\u00eda, cuando nos ponemos a los mandos del coche, suele producirse un <a href=\"https:\/\/drive-smart.com\/es\/blog\/2019\/02\/13\/mecanofilia-amor-coche\/\" target=\"_blank\" rel=\"noopener\"><strong>fen\u00f3meno paranormal<\/strong><\/a>. <strong>A m\u00ed me gusta catalogarlo como el daltonismo ilustrado<\/strong>. Daltonismo porque en cuanto nos ponemos en marcha, se nos presentan enormes dificultades para diferenciar los colores. E ilustrado porque me parece un apellido magn\u00edfico para el daltonismo. <strong>Es como que confundimos los colores, pero con clase.<\/strong>\u00a0<\/p>\n<p>Volvamos al d\u00e9ficit de interpretaci\u00f3n de colores. Tenemos que decir que esto es algo que <a href=\"https:\/\/drive-smart.com\/es\/blog\/2015\/02\/26\/que-hacemos-los-conductores-en-los-semaforos-en-rojo\/\" target=\"_blank\" rel=\"noopener\"><strong>s\u00f3lo se produce en los sem\u00e1foros.<\/strong><\/a> Esos aparatejos que se ubican en las intersecciones. Y su misi\u00f3n es regular el tr\u00e1fico de las ciudades. <strong>Verde, rojo y el m\u00e1s guay: el \u00e1mbar.<\/strong> Aunque la <strong>Educaci\u00f3n Vial<\/strong> en la teor\u00eda es la misma para todo el conjunto de espa\u00f1oles&#8230; Los andaluces, en la pr\u00e1ctica, le damos una vuelta de tuercas. Y aportamos algunas variaciones.<\/p>\n<p>Por ejemplo, el rojo significa <a href=\"https:\/\/drive-smart.com\/es\/blog\/2018\/11\/15\/conductores-madrid-prohibido-el-paso\/\" target=\"_blank\" rel=\"noopener\"><strong>prohibici\u00f3n al paso<\/strong><\/a>. Pero para nosotros es m\u00e1s un rojo con tintes verde esperanza. Porque justo cuando el sem\u00e1foro va a encenderse en este color, nos queda siempre la esperanza de pasar. Y pasamos. Sin mirar atr\u00e1s. <strong>Porque aunque est\u00e9 en rojo, estamos ya en medio y \u00abya que estamos\u00bb<\/strong>&#8230; Pues pisamos el acelerador aunque hayamos iniciado la marcha con el sem\u00e1foro en color tomate.\u00a0<\/p>\n<p>Sin embargo, <strong>el verde nos inspira tranquilidad<\/strong>. Es como un chute de tila. Y podemos ir a velocidad de tortuga mientras lo veamos. Por \u00faltimo, <strong>el \u00e1mbar, que significa precauci\u00f3n, nos altera.<\/strong> As\u00ed que en lugar de parar por su inminente cambio a rojo, aceleramos como si se nos fuera la vida en ello. <strong>Y aderezamos la situaci\u00f3n manifestando nuestra famosa triple negaci\u00f3n para afirmar contundentemente que pararnos no es una opci\u00f3n:<\/strong> <strong>\u00abNo ni n\u00e1\u00bb<\/strong>.<\/p>\n<h4><span style=\"color: #1d2d38;\"><strong>La paciencia<\/strong><\/span><\/h4>\n<p>Ya no es que tengamos poca. Es que la tenemos por estrenar. Cualquier situaci\u00f3n cuyo desenlace se demore en el tiempo m\u00e1s de lo normal, <strong>nos pone tan nervioso como un cantante con hipo<\/strong>. Cuando somos los culpables, nos callamos. Pero cuando es otro, <a href=\"https:\/\/drive-smart.com\/es\/blog\/2019\/01\/17\/razones-poner-cepo-inmovilizar-coche\/\" target=\"_blank\" rel=\"noopener\"><strong>entramos en c\u00f3lera.<\/strong><\/a> Ah\u00ed entra en juego la variaci\u00f3n geogr\u00e1fica del lenguaje. <strong>Al \u00abvenga ya\u00bb,<\/strong> se le adjunta un ramillete de nombramientos tales como <strong>&#8216;carajo&#8217;, &#8216;cabr\u00f3n&#8217; &#8216;cop\u00f3n&#8217;, &#8216;mamona&#8217;, &#8216;cojones&#8217;, &#8216;mamahostia&#8217; o &#8216;pollita&#8217;.\u00a0<\/strong><\/p>\n<p><strong>En los atascos lo pasamos fatal.<\/strong> Como se vaya formando un aglomeraci\u00f3n de coches, ya estamos esperando al primer toque de claxon.\u00a0<strong>El efecto domin\u00f3<\/strong> nada como pez en el agua en el momento en el que el primer coche lo presiona. Y debes sentirte dichoso porque sin comprar ninguna entrada, <strong>est\u00e1s asistiendo a un concierto mel\u00f3dico que ya quisiera la Filarm\u00f3nica de Viena.<\/strong> Dicho sea de paso, en Andaluc\u00eda la palabra &#8216;claxon&#8217; es tan inexistente como poner los intermitentes en las rotondas. Nosotros \u00abtocamos el pito\u00bb. Y se lo tocamos a quien no lo hace bien. Pero en ambos sentidos. <a href=\"https:\/\/drive-smart.com\/es\/blog\/2017\/02\/13\/me-pueden-multar-tocar-claxon\/\" target=\"_blank\" rel=\"noopener\"><strong>En el de apretar el claxon<\/strong><\/a> y en el de incordiar al conductor en cuesti\u00f3n.<\/p>\n<p>En los ceda al paso, muchas veces hacemos de todo, menos ceder el paso. A lo lejos vislumbramos el ceda. Pero cuando llegamos, el recuerdo de la se\u00f1al se nos esfuma. <strong>Y metemos el morro del coche en mitad de la intersecci\u00f3n<\/strong>, as\u00ed como demostrando quien es el que manda. Y claro, no s\u00f3lo pasamos primero, sino que por mucho que queramos <strong>ceder el paso<\/strong>, cuando medio coche est\u00e1 en la intersecci\u00f3n ya no podemos brindarle el paso al pr\u00f3jimo.\u00a0<\/p>\n<h4><span style=\"color: #1d2d38;\"><strong>Aqu\u00ed las comparaciones no son odiosas<\/strong><\/span><\/h4>\n<p><strong>Y es que la enciclopedia de comparaciones relacionadas con el motor es muy rica en cuanto a su variedad.<\/strong> No queremos caer en t\u00f3picos t\u00edpicos. Pero es que en el sur somos muy ingeniosos <a href=\"https:\/\/drive-smart.com\/es\/blog\/2019\/01\/30\/tuits-divertidos-guardia-civil\/\"><strong>a la hora del doble sentido<\/strong><\/a>. Cuando tienes el coche sucio, se han escuchado joyas como: <strong>\u00abEse coche tiene m\u00e1s mierda que el dormitorio de una gallina\u00bb, \u00ab\u00bfEst\u00e1s esperando a que llueva?\u00bb o \u00abSi eres as\u00ed en la intimidad, ll\u00e1mame\u00bb<\/strong>.<\/p>\n<p>Otro de los casos es cuando te montas en un coche y est\u00e1 equipado con lo justo. Por no tener no tiene ni alfombrillas. Y de ambientador tiene un paquete de chicles abierto. Cuando damos con este tipo de conductor, se le dice que\u00a0<strong>\u00abte gastas menos en el coche que un barco en frenos\u00bb, \u00abte gastas menos que un caramelo de m\u00e1rmol\u00bb o \u00abte gastas menos que la barandilla de un noveno\u00bb.<\/strong><\/p>\n<h4><span style=\"color: #1d2d38;\">Traductor de expresiones y conductas de Andaluc\u00eda<\/span><\/h4>\n<ul>\n<li>Saludo est\u00e1ndar: <strong>me cago en tu (inserte familiar de primer orden)<\/strong>\n<ul>\n<li>Sustantivos a a\u00f1adir al final del saludo muy andaluces:<strong> &#8216;carajo&#8217;, &#8216;cabr\u00f3n&#8217; &#8216;cop\u00f3n&#8217;, &#8216;mamona&#8217;, &#8216;cojones&#8217;, &#8216;mamahostia&#8217; o &#8216;pollita&#8217;.<\/strong><\/li>\n<\/ul>\n<\/li>\n<li>Cuidado si ves un coche <strong>con matr\u00edcula de fuera PORQUE VIENE A QUITARTE EL APARCAMIENTO.<\/strong><\/li>\n<li>En caso de atasco, <strong>siempre debes maldecir a todo el que est\u00e9 delante tuya.<\/strong><\/li>\n<li>Los sem\u00e1foros <strong>s\u00f3lo tienen un color&#8230; \u00a1el verde!<\/strong><\/li>\n<li>Los pasos de peatones <strong>est\u00e1n dibujados a lo largo de toda la carretera, porque cruzamos por donde nos apetezca.<\/strong><\/li>\n<li>Los STOP <strong>funcionan con car\u00e1cter retroactivo.<\/strong><\/li>\n<li>Los ceda el paso <strong>son como los Reyes Magos.<\/strong><\/li>\n<li>En autov\u00eda <strong>la velocidad\u00a0m\u00ednima es de 120&#8230; Y la m\u00e1xima 121.<\/strong><\/li>\n<li>El cambio de carril <strong>se hace sin mirar por los retrovisores.<\/strong><\/li>\n<li>Los adelantamientos <strong>van acompa\u00f1ados de una miradita tal que as\u00ed<\/strong>\ud83d\ude0f<\/li>\n<li>Sabes que el conductor tiene los 8 apellidos andaluces <strong>si los intermitentes brillan&#8230; por su ausencia.<\/strong><\/li>\n<li>Si te dicen <strong>\u201c\u00bfd\u00f3nde vas?\u201d no pienses que nos interesamos en el destino de tu viaje. Esto significa que vas m\u00e1s r\u00e1pido de lo debido.<\/strong><\/li>\n<\/ul>\n<p>A toda la legi\u00f3n de usuarios <span style=\"color: #20c69b;\"><strong>:DriveSmart<\/strong><\/span> de Andaluc\u00eda&#8230; <strong>\u00bfPod\u00e9is aportar otras conductas que suceden por vuestra zona? \u00bfO expresiones que hay\u00e1is escuchado en situaciones parecidas? Estamos locos por leeros, as\u00ed que&#8230; \u00a1d\u00e9janos tu comentario!<\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Andaluc\u00eda es una tierra especial. Y no lo digo porque me hayan encomendado este art\u00edculo. Tampoco tiene nada que ver que sea m\u00e1s andaluz que el gazpacho\ud83d\ude44. Ya lo han dicho otros. La idiosincrasia de nuestra tierra ha sido explicada por paisanos como\u00a0Averroes, S\u00e9neca o Juan Luis de Tarifa. Ha inspirado a genios como Antonio [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":23239,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[92],"tags":[1845,1846,1914,137,179,1086,1915,487,1847,1917,1916],"class_list":["post-22914","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-para-ti-conductor","tag-andalucia","tag-andaluz","tag-conductas","tag-conductor","tag-drive-smart","tag-drivesmart","tag-expresiones","tag-humor","tag-manual-general","tag-risas","tag-sur"],"_links":{"self":[{"href":"https:\/\/drive-smart.com\/es\/wp-json\/wp\/v2\/posts\/22914","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/drive-smart.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/drive-smart.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/drive-smart.com\/es\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/drive-smart.com\/es\/wp-json\/wp\/v2\/comments?post=22914"}],"version-history":[{"count":16,"href":"https:\/\/drive-smart.com\/es\/wp-json\/wp\/v2\/posts\/22914\/revisions"}],"predecessor-version":[{"id":25349,"href":"https:\/\/drive-smart.com\/es\/wp-json\/wp\/v2\/posts\/22914\/revisions\/25349"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/drive-smart.com\/es\/wp-json\/wp\/v2\/media\/23239"}],"wp:attachment":[{"href":"https:\/\/drive-smart.com\/es\/wp-json\/wp\/v2\/media?parent=22914"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/drive-smart.com\/es\/wp-json\/wp\/v2\/categories?post=22914"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/drive-smart.com\/es\/wp-json\/wp\/v2\/tags?post=22914"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}